{"id":353997,"date":"2023-11-23T10:52:09","date_gmt":"2023-11-23T10:52:13","guid":{"rendered":"https:\/\/www.erresse-shop.it\/?post_type=product&#038;p=353997"},"modified":"2023-11-23T11:02:02","modified_gmt":"2023-11-23T11:02:02","slug":"seletti-lampara-led-mentira-gris","status":"publish","type":"product","link":"https:\/\/www.erresse-shop.it\/es\/shop\/mobiliario\/lamparas\/seletti-lampara-led-mentira-gris\/","title":{"rendered":"SELETTI L\u00e1mpara Led Mentira Gris"},"content":{"rendered":"<p>Un objeto que trae a la mente recuerdos antiguos, cenas a la luz de las velas, cosas simples pero muy valiosas. La Mentira Lamp te har\u00e1 revivir estos momentos con un solo clic. Puedes llevarla donde quieras para hacer que cada lugar sea m\u00e1gico.<\/p>\n<p>L\u00e1mpara<\/p>\n<p>Dise\u00f1o: BLOW<\/p>\n<p>Material: Resina de Resina<\/p>\n<p>Dimensiones: cm. 22 x 28 h. 31 | 8.6&#8243; x 11&#8243; x h. 12,2&#8243;<\/p>\n<p>Bater\u00eda port\u00e1til recargable<\/p>\n<p>Bombilla led 3W \/ 180 Lumen \/ 2200 K \/ E 14<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un objeto que trae a la mente recuerdos antiguos, cenas a la luz de las velas, cosas simples pero muy<\/p>\n","protected":false},"featured_media":354004,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_cat":[16017,16016],"product_tag":[16236,16237,18078,25023],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v18.6 (Yoast SEO v19.13) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>SELETTI L\u00e1mpara Led Mentira Gris - Erresse Shop<\/title>\n<meta name=\"description\" content=\"Un objeto que trae a la mente recuerdos antiguos, cenas a la luz de las velas, cosas simples pero muy valiosas. La Mentira Lamp te har\u00e1 revivir estos\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.erresse-shop.it\/es\/shop\/mobiliario\/lamparas\/seletti-lampara-led-mentira-gris\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SELETTI L\u00e1mpara Led Mentira Gris\" \/>\n<meta property=\"og:description\" content=\"Un objeto que trae a la mente recuerdos antiguos, cenas a la luz de las velas, cosas simples pero muy valiosas. La Mentira Lamp te har\u00e1 revivir estos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.erresse-shop.it\/es\/shop\/mobiliario\/lamparas\/seletti-lampara-led-mentira-gris\/\" \/>\n<meta property=\"og:site_name\" content=\"Erresse Shop\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-23T11:02:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.erresse-shop.it\/wp-content\/uploads\/2023\/11\/seletti-lampada-led-grimm-13111.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.erresse-shop.it\/es\/shop\/mobiliario\/lamparas\/seletti-lampara-led-mentira-gris\/\",\"url\":\"https:\/\/www.erresse-shop.it\/es\/shop\/mobiliario\/lamparas\/seletti-lampara-led-mentira-gris\/\",\"name\":\"SELETTI L\u00e1mpara Led Mentira Gris - Erresse Shop\",\"isPartOf\":{\"@id\":\"https:\/\/www.erresse-shop.it\/es\/#website\"},\"datePublished\":\"2023-11-23T10:52:13+00:00\",\"dateModified\":\"2023-11-23T11:02:02+00:00\",\"description\":\"Un objeto que trae a la mente recuerdos antiguos, cenas a la luz de las velas, cosas simples pero muy valiosas. La Mentira Lamp te har\u00e1 revivir estos\",\"breadcrumb\":{\"@id\":\"https:\/\/www.erresse-shop.it\/es\/shop\/mobiliario\/lamparas\/seletti-lampara-led-mentira-gris\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.erresse-shop.it\/es\/shop\/mobiliario\/lamparas\/seletti-lampara-led-mentira-gris\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.erresse-shop.it\/es\/shop\/mobiliario\/lamparas\/seletti-lampara-led-mentira-gris\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.erresse-shop.it\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/www.erresse-shop.it\/es\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"SELETTI L\u00e1mpara Led Mentira Gris\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.erresse-shop.it\/es\/#website\",\"url\":\"https:\/\/www.erresse-shop.it\/es\/\",\"name\":\"Erresse Shop\",\"description\":\"Articoli di qualit\u00e0 per la casa\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.erresse-shop.it\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"SELETTI L\u00e1mpara Led Mentira Gris - Erresse Shop","description":"Un objeto que trae a la mente recuerdos antiguos, cenas a la luz de las velas, cosas simples pero muy valiosas. La Mentira Lamp te har\u00e1 revivir estos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.erresse-shop.it\/es\/shop\/mobiliario\/lamparas\/seletti-lampara-led-mentira-gris\/","og_locale":"es_ES","og_type":"article","og_title":"SELETTI L\u00e1mpara Led Mentira Gris","og_description":"Un objeto que trae a la mente recuerdos antiguos, cenas a la luz de las velas, cosas simples pero muy valiosas. La Mentira Lamp te har\u00e1 revivir estos","og_url":"https:\/\/www.erresse-shop.it\/es\/shop\/mobiliario\/lamparas\/seletti-lampara-led-mentira-gris\/","og_site_name":"Erresse Shop","article_modified_time":"2023-11-23T11:02:02+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/www.erresse-shop.it\/wp-content\/uploads\/2023\/11\/seletti-lampada-led-grimm-13111.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.erresse-shop.it\/es\/shop\/mobiliario\/lamparas\/seletti-lampara-led-mentira-gris\/","url":"https:\/\/www.erresse-shop.it\/es\/shop\/mobiliario\/lamparas\/seletti-lampara-led-mentira-gris\/","name":"SELETTI L\u00e1mpara Led Mentira Gris - Erresse Shop","isPartOf":{"@id":"https:\/\/www.erresse-shop.it\/es\/#website"},"datePublished":"2023-11-23T10:52:13+00:00","dateModified":"2023-11-23T11:02:02+00:00","description":"Un objeto que trae a la mente recuerdos antiguos, cenas a la luz de las velas, cosas simples pero muy valiosas. La Mentira Lamp te har\u00e1 revivir estos","breadcrumb":{"@id":"https:\/\/www.erresse-shop.it\/es\/shop\/mobiliario\/lamparas\/seletti-lampara-led-mentira-gris\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.erresse-shop.it\/es\/shop\/mobiliario\/lamparas\/seletti-lampara-led-mentira-gris\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.erresse-shop.it\/es\/shop\/mobiliario\/lamparas\/seletti-lampara-led-mentira-gris\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.erresse-shop.it\/es\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.erresse-shop.it\/es\/shop\/"},{"@type":"ListItem","position":3,"name":"SELETTI L\u00e1mpara Led Mentira Gris"}]},{"@type":"WebSite","@id":"https:\/\/www.erresse-shop.it\/es\/#website","url":"https:\/\/www.erresse-shop.it\/es\/","name":"Erresse Shop","description":"Articoli di qualit\u00e0 per la casa","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.erresse-shop.it\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"}]}},"df_price":89.10000000000001,"df_sale_price":89.10000000000001,"df_regular_price":198,"df_image_link":"https:\/\/www.erresse-shop.it\/wp-content\/uploads\/2023\/11\/seletti-lampada-led-grimm-13111-300x300.jpg","_links":{"self":[{"href":"https:\/\/www.erresse-shop.it\/es\/wp-json\/wp\/v2\/product\/353997"}],"collection":[{"href":"https:\/\/www.erresse-shop.it\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.erresse-shop.it\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.erresse-shop.it\/es\/wp-json\/wp\/v2\/media\/354004"}],"wp:attachment":[{"href":"https:\/\/www.erresse-shop.it\/es\/wp-json\/wp\/v2\/media?parent=353997"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.erresse-shop.it\/es\/wp-json\/wp\/v2\/product_cat?post=353997"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.erresse-shop.it\/es\/wp-json\/wp\/v2\/product_tag?post=353997"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}