{"id":494477,"date":"2025-04-23T08:18:43","date_gmt":"2025-04-23T08:18:44","guid":{"rendered":"https:\/\/www.erresse-shop.it\/?post_type=product&#038;p=494477"},"modified":"2026-02-10T10:28:21","modified_gmt":"2026-02-10T10:28:21","slug":"vista-alegre-accento-undurchsichtiger-tisch","status":"publish","type":"product","link":"https:\/\/www.erresse-shop.it\/de\/shop\/einrichtung-haus\/tische-und-couchtische\/vista-alegre-accento-undurchsichtiger-tisch\/","title":{"rendered":"VISTA ALEGRE Accento Undurchsichtiger Tisch"},"content":{"rendered":"<p>Der Tisch aus der Accento-Kollektion von Vista Alegre, der in Zusammenarbeit mit Pininfarina entstand, ist mit edlen Materialien wie Leder, Holz und Marmor von Hand gefertigt. Inspiriert von den Luxussportwagen der 60er und 70er Jahre ist es Teil einer Kollektion zur Feier des 200. Jubil\u00e4ums von Vista Alegre. M\u00f6bel wie Sitze, Tische und Sideboards kombinieren Keramikdetails und Automobildesign und sind eine Hommage an das Erbe von Pininfarina.<\/p>\n<p>H\u00f6he: 790 mm<br \/>\nL\u00e4nge: 2409 mm<br \/>\nBreite: 1175 mm<\/p>\n<p>Anthrazit gebeiztes Eschenholz<br \/>\nSchwarzer Marquina-Marmor (mattes Finish)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Tisch aus der Accento-Kollektion von Vista Alegre, der in Zusammenarbeit mit Pininfarina entstand, ist mit edlen Materialien wie Leder,<\/p>\n","protected":false},"featured_media":494487,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_cat":[6817,24383],"product_tag":[25027,24604,24681,25022],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v18.6 (Yoast SEO v19.13) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>VISTA ALEGRE Accento Undurchsichtiger Tisch - Erresse Shop<\/title>\n<meta name=\"description\" content=\"Der Tisch aus der Accento-Kollektion von Vista Alegre, der in Zusammenarbeit mit Pininfarina entstand, ist mit edlen Materialien wie Leder, Holz und\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.erresse-shop.it\/de\/shop\/einrichtung-haus\/tische-und-couchtische\/vista-alegre-accento-undurchsichtiger-tisch\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"VISTA ALEGRE Accento Undurchsichtiger Tisch\" \/>\n<meta property=\"og:description\" content=\"Der Tisch aus der Accento-Kollektion von Vista Alegre, der in Zusammenarbeit mit Pininfarina entstand, ist mit edlen Materialien wie Leder, Holz und\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.erresse-shop.it\/de\/shop\/einrichtung-haus\/tische-und-couchtische\/vista-alegre-accento-undurchsichtiger-tisch\/\" \/>\n<meta property=\"og:site_name\" content=\"Erresse Shop\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-10T10:28:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.erresse-shop.it\/wp-content\/uploads\/2025\/04\/VISTA-ALEGRE-Accento-Tavolo-Opaco.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.erresse-shop.it\/de\/shop\/einrichtung-haus\/tische-und-couchtische\/vista-alegre-accento-undurchsichtiger-tisch\/\",\"url\":\"https:\/\/www.erresse-shop.it\/de\/shop\/einrichtung-haus\/tische-und-couchtische\/vista-alegre-accento-undurchsichtiger-tisch\/\",\"name\":\"VISTA ALEGRE Accento Undurchsichtiger Tisch - Erresse Shop\",\"isPartOf\":{\"@id\":\"https:\/\/www.erresse-shop.it\/de\/#website\"},\"datePublished\":\"2025-04-23T08:18:44+00:00\",\"dateModified\":\"2026-02-10T10:28:21+00:00\",\"description\":\"Der Tisch aus der Accento-Kollektion von Vista Alegre, der in Zusammenarbeit mit Pininfarina entstand, ist mit edlen Materialien wie Leder, Holz und\",\"breadcrumb\":{\"@id\":\"https:\/\/www.erresse-shop.it\/de\/shop\/einrichtung-haus\/tische-und-couchtische\/vista-alegre-accento-undurchsichtiger-tisch\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.erresse-shop.it\/de\/shop\/einrichtung-haus\/tische-und-couchtische\/vista-alegre-accento-undurchsichtiger-tisch\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.erresse-shop.it\/de\/shop\/einrichtung-haus\/tische-und-couchtische\/vista-alegre-accento-undurchsichtiger-tisch\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.erresse-shop.it\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/www.erresse-shop.it\/de\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"VISTA ALEGRE Accento Undurchsichtiger Tisch\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.erresse-shop.it\/de\/#website\",\"url\":\"https:\/\/www.erresse-shop.it\/de\/\",\"name\":\"Erresse Shop\",\"description\":\"Articoli di qualit\u00e0 per la casa\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.erresse-shop.it\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de-DE\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"VISTA ALEGRE Accento Undurchsichtiger Tisch - Erresse Shop","description":"Der Tisch aus der Accento-Kollektion von Vista Alegre, der in Zusammenarbeit mit Pininfarina entstand, ist mit edlen Materialien wie Leder, Holz und","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.erresse-shop.it\/de\/shop\/einrichtung-haus\/tische-und-couchtische\/vista-alegre-accento-undurchsichtiger-tisch\/","og_locale":"de_DE","og_type":"article","og_title":"VISTA ALEGRE Accento Undurchsichtiger Tisch","og_description":"Der Tisch aus der Accento-Kollektion von Vista Alegre, der in Zusammenarbeit mit Pininfarina entstand, ist mit edlen Materialien wie Leder, Holz und","og_url":"https:\/\/www.erresse-shop.it\/de\/shop\/einrichtung-haus\/tische-und-couchtische\/vista-alegre-accento-undurchsichtiger-tisch\/","og_site_name":"Erresse Shop","article_modified_time":"2026-02-10T10:28:21+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/www.erresse-shop.it\/wp-content\/uploads\/2025\/04\/VISTA-ALEGRE-Accento-Tavolo-Opaco.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.erresse-shop.it\/de\/shop\/einrichtung-haus\/tische-und-couchtische\/vista-alegre-accento-undurchsichtiger-tisch\/","url":"https:\/\/www.erresse-shop.it\/de\/shop\/einrichtung-haus\/tische-und-couchtische\/vista-alegre-accento-undurchsichtiger-tisch\/","name":"VISTA ALEGRE Accento Undurchsichtiger Tisch - Erresse Shop","isPartOf":{"@id":"https:\/\/www.erresse-shop.it\/de\/#website"},"datePublished":"2025-04-23T08:18:44+00:00","dateModified":"2026-02-10T10:28:21+00:00","description":"Der Tisch aus der Accento-Kollektion von Vista Alegre, der in Zusammenarbeit mit Pininfarina entstand, ist mit edlen Materialien wie Leder, Holz und","breadcrumb":{"@id":"https:\/\/www.erresse-shop.it\/de\/shop\/einrichtung-haus\/tische-und-couchtische\/vista-alegre-accento-undurchsichtiger-tisch\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.erresse-shop.it\/de\/shop\/einrichtung-haus\/tische-und-couchtische\/vista-alegre-accento-undurchsichtiger-tisch\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.erresse-shop.it\/de\/shop\/einrichtung-haus\/tische-und-couchtische\/vista-alegre-accento-undurchsichtiger-tisch\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.erresse-shop.it\/de\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.erresse-shop.it\/de\/shop\/"},{"@type":"ListItem","position":3,"name":"VISTA ALEGRE Accento Undurchsichtiger Tisch"}]},{"@type":"WebSite","@id":"https:\/\/www.erresse-shop.it\/de\/#website","url":"https:\/\/www.erresse-shop.it\/de\/","name":"Erresse Shop","description":"Articoli di qualit\u00e0 per la casa","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.erresse-shop.it\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de-DE"}]}},"df_price":4795.083,"df_sale_price":4795.083,"df_regular_price":10655.74,"df_image_link":"https:\/\/www.erresse-shop.it\/wp-content\/uploads\/2025\/04\/VISTA-ALEGRE-Accento-Tavolo-Opaco-300x300.jpg","_links":{"self":[{"href":"https:\/\/www.erresse-shop.it\/de\/wp-json\/wp\/v2\/product\/494477"}],"collection":[{"href":"https:\/\/www.erresse-shop.it\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.erresse-shop.it\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.erresse-shop.it\/de\/wp-json\/wp\/v2\/media\/494487"}],"wp:attachment":[{"href":"https:\/\/www.erresse-shop.it\/de\/wp-json\/wp\/v2\/media?parent=494477"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.erresse-shop.it\/de\/wp-json\/wp\/v2\/product_cat?post=494477"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.erresse-shop.it\/de\/wp-json\/wp\/v2\/product_tag?post=494477"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}